{"id":1940,"count":1,"description":"","link":"https:\/\/mysouldrops.eu\/sk\/tag\/nemzetkozi-indulas\/","name":"Medzin\u00e1rodn\u00fd odchod","slug":"narodny-filmovy-pochod","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nemzetk\u00f6zi indul\u00e1s Arch\u00edvum - Souldrops International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mysouldrops.eu\/sk\/tag\/narodny-filmovy-pochod\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nemzetk\u00f6zi indul\u00e1s Arch\u00edvum - Souldrops International\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mysouldrops.eu\/sk\/tag\/narodny-filmovy-pochod\/\" \/>\n<meta property=\"og:site_name\" content=\"Souldrops International\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/sk\\\/tag\\\/nemzetkozi-indulas\\\/\",\"url\":\"https:\\\/\\\/mysouldrops.eu\\\/sk\\\/tag\\\/nemzetkozi-indulas\\\/\",\"name\":\"Nemzetk\u00f6zi indul\u00e1s Arch\u00edvum - Souldrops International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/sk\\\/tag\\\/nemzetkozi-indulas\\\/#breadcrumb\"},\"inLanguage\":\"sk-SK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/sk\\\/tag\\\/nemzetkozi-indulas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/mysouldrops.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nemzetk\u00f6zi indul\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/#website\",\"url\":\"https:\\\/\\\/mysouldrops.eu\\\/\",\"name\":\"Souldrops International\",\"description\":\"A Souldrops egy k\u00f6rnyezettudatos tiszt\u00edt\u00f3szerm\u00e1rka, amely term\u00e9szetes \u00f6sszetev\u0151kkel \u00e9s st\u00edlusos szeml\u00e9lettel teszi tiszt\u00e1bb\u00e1 a vil\u00e1got \u2013 k\u00edv\u00fcl \u00e9s bel\u00fcl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mysouldrops.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nemzetk\u00f6zi indul\u00e1s Arch\u00edvum - Souldrops International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mysouldrops.eu\/sk\/tag\/narodny-filmovy-pochod\/","og_locale":"sk_SK","og_type":"article","og_title":"Nemzetk\u00f6zi indul\u00e1s Arch\u00edvum - Souldrops International","og_url":"https:\/\/mysouldrops.eu\/sk\/tag\/narodny-filmovy-pochod\/","og_site_name":"Souldrops International","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mysouldrops.eu\/sk\/tag\/nemzetkozi-indulas\/","url":"https:\/\/mysouldrops.eu\/sk\/tag\/nemzetkozi-indulas\/","name":"Medzin\u00e1rodn\u00e9 odlety Archives - Souldrops International","isPartOf":{"@id":"https:\/\/mysouldrops.eu\/#website"},"breadcrumb":{"@id":"https:\/\/mysouldrops.eu\/sk\/tag\/nemzetkozi-indulas\/#breadcrumb"},"inLanguage":"sk-SK"},{"@type":"BreadcrumbList","@id":"https:\/\/mysouldrops.eu\/sk\/tag\/nemzetkozi-indulas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/mysouldrops.eu\/"},{"@type":"ListItem","position":2,"name":"Nemzetk\u00f6zi indul\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/mysouldrops.eu\/#website","url":"https:\/\/mysouldrops.eu\/","name":"Souldrops International","description":"Souldrops je ekologick\u00e1 zna\u010dka \u010distiacich prostriedkov, ktor\u00e1 vyu\u017e\u00edva pr\u00edrodn\u00e9 zlo\u017eky a \u0161t\u00fdlov\u00fd pr\u00edstup, aby bol svet \u010distej\u0161\u00ed - zvn\u00fatra aj zvonku.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mysouldrops.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"}]}},"_links":{"self":[{"href":"https:\/\/mysouldrops.eu\/sk\/wp-json\/wp\/v2\/tags\/1940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mysouldrops.eu\/sk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mysouldrops.eu\/sk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mysouldrops.eu\/sk\/wp-json\/wp\/v2\/posts?tags=1940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}