{"id":267682164,"name":"Souldrops Admin","url":"http:\/\/souldrops0.wordpress.com","description":"","link":"https:\/\/mysouldrops.eu\/sv\/author\/souldropsadmin25\/","slug":"souldropsadmin25","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=24&d=identicon&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=48&d=identicon&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=96&d=identicon&r=g"},"meta":{"jetpack_donation_warning_dismissed":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Souldrops Admin, Szerz\u0151 | Souldrops International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mysouldrops.eu\/sv\/forfattare\/souldropsadmin25\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Souldrops Admin, Szerz\u0151 | Souldrops International\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mysouldrops.eu\/sv\/forfattare\/souldropsadmin25\/\" \/>\n<meta property=\"og:site_name\" content=\"Souldrops International\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=500&d=identicon&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/author\\\/souldropsadmin25\\\/\",\"url\":\"https:\\\/\\\/mysouldrops.eu\\\/author\\\/souldropsadmin25\\\/\",\"name\":\"Souldrops Admin, Szerz\u0151 | Souldrops International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/author\\\/souldropsadmin25\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mysouldrops.eu\\\/author\\\/souldropsadmin25\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/author\\\/souldropsadmin25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/mysouldrops.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arch\u00edvumban Souldrops Admin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/#website\",\"url\":\"https:\\\/\\\/mysouldrops.eu\\\/\",\"name\":\"Souldrops International\",\"description\":\"A Souldrops egy k\u00f6rnyezettudatos tiszt\u00edt\u00f3szerm\u00e1rka, amely term\u00e9szetes \u00f6sszetev\u0151kkel \u00e9s st\u00edlusos szeml\u00e9lettel teszi tiszt\u00e1bb\u00e1 a vil\u00e1got \u2013 k\u00edv\u00fcl \u00e9s bel\u00fcl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mysouldrops.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/#\\\/schema\\\/person\\\/82b8b81b6c60fbdbecb82c555a36b773\",\"name\":\"Souldrops Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=96&d=identicon&r=g\",\"caption\":\"Souldrops Admin\"},\"sameAs\":[\"http:\\\/\\\/souldrops0.wordpress.com\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mysouldrops.eu\\\/author\\\/souldropsadmin25\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Souldrops Admin, Szerz\u0151 | Souldrops International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mysouldrops.eu\/sv\/forfattare\/souldropsadmin25\/","og_locale":"sv_SE","og_type":"profile","og_title":"Souldrops Admin, Szerz\u0151 | Souldrops International","og_url":"https:\/\/mysouldrops.eu\/sv\/forfattare\/souldropsadmin25\/","og_site_name":"Souldrops International","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=500&d=identicon&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/mysouldrops.eu\/author\/souldropsadmin25\/","url":"https:\/\/mysouldrops.eu\/author\/souldropsadmin25\/","name":"Souldrops Admin, Szerz\u0151 | Souldrops International","isPartOf":{"@id":"https:\/\/mysouldrops.eu\/#website"},"breadcrumb":{"@id":"https:\/\/mysouldrops.eu\/author\/souldropsadmin25\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mysouldrops.eu\/author\/souldropsadmin25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mysouldrops.eu\/author\/souldropsadmin25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/mysouldrops.eu\/"},{"@type":"ListItem","position":2,"name":"Arch\u00edvumban Souldrops Admin"}]},{"@type":"WebSite","@id":"https:\/\/mysouldrops.eu\/#website","url":"https:\/\/mysouldrops.eu\/","name":"Souldrops International","description":"A Souldrops egy k\u00f6rnyezettudatos tiszt\u00edt\u00f3szerm\u00e1rka, amely term\u00e9szetes \u00f6sszetev\u0151kkel \u00e9s st\u00edlusos szeml\u00e9lettel teszi tiszt\u00e1bb\u00e1 a vil\u00e1got \u2013 k\u00edv\u00fcl \u00e9s bel\u00fcl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mysouldrops.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Person","@id":"https:\/\/mysouldrops.eu\/#\/schema\/person\/82b8b81b6c60fbdbecb82c555a36b773","name":"Souldrops Admin","image":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/459ad38fb415a692d68e04808e14b045b4d871e240c8b9ae32778137950793ca?s=96&d=identicon&r=g","caption":"Souldrops Admin"},"sameAs":["http:\/\/souldrops0.wordpress.com"],"mainEntityOfPage":{"@id":"https:\/\/mysouldrops.eu\/author\/souldropsadmin25\/"}}]}},"is_super_admin":true,"woocommerce_meta":{"variable_product_tour_shown":"yes","wc_payments_overview_inbox_last_read":"1764405282405","wc_payments_transactions_hidden_columns":"[\"currency\",\"customer_email\",\"customer_country\",\"risk_level\",\"deposit_id\"]","wc_payments_transactions_blocked_hidden_columns":"","wc_payments_transactions_risk_review_hidden_columns":"","wc_payments_transactions_uncaptured_hidden_columns":"","wc_payments_payouts_hidden_columns":"","wc_payments_disputes_hidden_columns":"","wc_payments_documents_hidden_columns":"","wc_payments_wporg_review_2025_prompt_dismissed":"1761568743073","wc_payments_review_prompt_dismissed":"","wc_payments_review_prompt_maybe_later":"","activity_panel_inbox_last_read":"","activity_panel_reviews_last_read":"","categories_report_columns":"","coupons_report_columns":"","customers_report_columns":"","orders_report_columns":"[\"customer_type\",\"num_items_sold\"]","products_report_columns":"","revenue_report_columns":"","taxes_report_columns":"","variations_report_columns":"","dashboard_sections":"[{\"key\":\"store-performance\",\"title\":\"Teljes\u00edtm\u00e9ny\",\"isVisible\":true,\"hiddenBlocks\":[\"coupons\/orders_count\",\"downloads\/download_count\",\"taxes\/order_tax\",\"taxes\/total_tax\",\"taxes\/shipping_tax\",\"revenue\/shipping\",\"revenue\/refunds\",\"revenue\/gross_sales\"]},{\"key\":\"charts\",\"title\":\"Diagramok\",\"isVisible\":true,\"hiddenBlocks\":[\"orders_avg_order_value\",\"avg_items_per_order\",\"products_items_sold\",\"revenue_refunds\",\"coupons_amount\",\"coupons_orders_count\",\"revenue_shipping\",\"taxes_total_tax\",\"taxes_order_tax\",\"taxes_shipping_tax\",\"downloads_download_count\"]},{\"key\":\"leaderboards\",\"title\":\"Toplist\u00e1k\",\"isVisible\":true,\"hiddenBlocks\":[\"coupons\",\"customers\"]}]","dashboard_chart_type":"","dashboard_chart_interval":"","dashboard_leaderboard_rows":"","order_attribution_install_banner_dismissed":"","scheduled_updates_promotion_notice_dismissed":"","homepage_layout":"two_columns","homepage_stats":"","task_list_tracked_started_tasks":"{\"payments\":2}","android_app_banner_dismissed":"","launch_your_store_tour_hidden":"","coming_soon_banner_dismissed":""},"_links":{"self":[{"href":"https:\/\/mysouldrops.eu\/sv\/wp-json\/wp\/v2\/users\/267682164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mysouldrops.eu\/sv\/wp-json\/wp\/v2\/users"}]}}